{"id":18291,"date":"2019-05-27T11:38:04","date_gmt":"2019-05-27T11:38:04","guid":{"rendered":"https:\/\/fuster-associates.com\/?p=18291"},"modified":"2020-04-06T11:49:37","modified_gmt":"2020-04-06T11:49:37","slug":"nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention","status":"publish","type":"post","link":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/","title":{"rendered":"Nouveaux contrats de bail en Espagne &#8211; A quoi devez-vous faire attention ?"},"content":{"rendered":"<h2>Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.<\/h2>\n<p>Il s&rsquo;agit d&rsquo;une traduction automatique en attente de r\u00e9vision.<\/p>\n<p>Le Conseil permanent du Tribunal g\u00e9n\u00e9ral espagnol a approuv\u00e9 la validation du d\u00e9cret-loi royal 7\/2019 sur les mesures urgentes en mati\u00e8re de logement et de loyer, qui a \u00e9t\u00e9 adopt\u00e9 par le Conseil des ministres le 1er mars.<\/p>\n<p>Qu&rsquo;est-ce que tout cela signifie pour les bailleurs et\/ou les locataires comme vous ?<\/p>\n<p><strong>Dur\u00e9e de la prolongation du contrat &#8211; entre 5 et 7 ans<\/strong><\/p>\n<p>La p\u00e9riode de prolongation obligatoire des contrats de location de logement varie entre 3 et 5 ans.<\/p>\n<p>Si le propri\u00e9taire est une personne morale, la dur\u00e9e est port\u00e9e \u00e0 7 ans.<\/p>\n<p>La dur\u00e9e du contrat est en th\u00e9orie laiss\u00e9e \u00e0 la discr\u00e9tion des parties, mais s&rsquo;il est sign\u00e9 pour une dur\u00e9e inf\u00e9rieure \u00e0 5 ans, le locataire a le droit de le prolonger ann\u00e9e apr\u00e8s ann\u00e9e jusqu&rsquo;\u00e0 la fin des 5 ans du contrat, ou 7 ans lorsque le bailleur est une personne morale.<\/p>\n<p>La p\u00e9riode d&rsquo;extension pr\u00e9sum\u00e9e de 1 \u00e0 3 ans est \u00e9galement prolong\u00e9e. Ainsi, apr\u00e8s la fin des 5 ans (ou 7 ans si le bailleur est une personne morale), si aucune des parties ne communique \u00e0 temps \u00e0 l&rsquo;autre partie son intention de l&rsquo;annuler, une nouvelle p\u00e9riode commencera avec le droit du locataire de prolonger le contrat ann\u00e9e apr\u00e8s ann\u00e9e jusqu&rsquo;\u00e0 la fin des trois ans.<\/p>\n<p>Attention !<\/p>\n<p>Le d\u00e9lai pour communiquer la r\u00e9siliation du contrat \u00e0 la fin de la p\u00e9riode initiale de cinq ans a \u00e9galement \u00e9t\u00e9 prolong\u00e9.<\/p>\n<p>Le propri\u00e9taire doit le notifier 4 mois \u00e0 l&rsquo;avance, et le locataire 2.<\/p>\n<p><strong>Les changements de prix des loyers sont limit\u00e9s \u00e0 l&rsquo;IPC annuel<\/strong><\/p>\n<p>La libert\u00e9 d&rsquo;alliance est formellement reconnue pour \u00e9tablir la mani\u00e8re dont le loyer sera actualis\u00e9 chaque ann\u00e9e.<\/p>\n<p>En l&rsquo;absence d&rsquo;un accord, le loyer ne sera pas actualis\u00e9.<\/p>\n<p>Dans tous les cas, l&rsquo;augmentation du nouveau loyer actualis\u00e9 sera limit\u00e9e par l&rsquo;IPC annuel \u00e0 la date de chaque actualisation. En d&rsquo;autres termes, pendant la dur\u00e9e du contrat &#8211; et au moins pendant les cinq ou sept ann\u00e9es de la dur\u00e9e initiale &#8211; le loyer ne sera mis \u00e0 jour qu&rsquo;en fonction des niveaux maximums de l&rsquo;IPC.<\/p>\n<p><strong>R\u00e9cup\u00e9rer le bien par n\u00e9cessit\u00e9 est devenu plus compliqu\u00e9<\/strong><\/p>\n<p>Pour \u00e9viter la prolongation obligatoire du contrat apr\u00e8s un an au cas o\u00f9 le propri\u00e9taire ou un parent proche doit vivre dans la propri\u00e9t\u00e9, il est d\u00e9sormais exig\u00e9 que le contrat inclue express\u00e9ment la n\u00e9cessit\u00e9 d&rsquo;occuper la maison lou\u00e9e avant la fin des cinq ans.<\/p>\n<p>Il est imp\u00e9ratif qu&rsquo;il y ait un besoin &#8211; et que celui-ci soit enregistr\u00e9 comme tel &#8211; de l&rsquo;affecter \u00e0 un logement permanent pour le propri\u00e9taire ou ses proches au premier degr\u00e9 de consanguinit\u00e9 ou en vue d&rsquo;une adoption ou pour son conjoint en cas de s\u00e9paration d\u00e9finitive, de divorce ou d&rsquo;annulation du mariage.<\/p>\n<p>L&rsquo;objectif de cet arr\u00eat est de garantir que cette excuse ne soit pas utilis\u00e9e pour mettre fin \u00e0 un contrat de location. C&rsquo;est pourquoi elle demande au propri\u00e9taire de communiquer son besoin de r\u00e9cup\u00e9rer le bien deux mois \u00e0 l&rsquo;avance, en pr\u00e9cisant la cause. Les causes de force majeure peuvent justifier qu&rsquo;une fois la maison lib\u00e9r\u00e9e, elle n&rsquo;aurait pas \u00e9t\u00e9 effectivement occup\u00e9e par le propri\u00e9taire trois mois plus tard.<\/p>\n<p><strong>Limitation des garanties de cautionnement suppl\u00e9mentaires<\/strong><\/p>\n<p>Des garanties de cautionnement suppl\u00e9mentaires sont impos\u00e9es jusqu&rsquo;\u00e0 un maximum de deux mois, sauf pour les contrats \u00e0 long terme.<\/p>\n<p>Les locataires ne seront pas oblig\u00e9s de payer plus de trois mensualit\u00e9s de loyer \u00e0 titre de garantie : le d\u00e9p\u00f4t l\u00e9gal d&rsquo;un mois (pour les loyers de logement) plus un maximum de deux mensualit\u00e9s suppl\u00e9mentaires \u00e0 titre de garantie suppl\u00e9mentaire.<\/p>\n<p>En revanche, il est \u00e9tabli que si le bailleur est une personne morale, les frais de gestion immobili\u00e8re et de formalisation du contrat seront \u00e0 la charge du bailleur. Rien n&rsquo;est dit pour les bailleurs qui sont des personnes physiques, bien que le principe g\u00e9n\u00e9ral selon lequel la commission de l&rsquo;agence doit \u00eatre pay\u00e9e par la partie qui a contract\u00e9 ses services tende \u00e0 pr\u00e9valoir.<\/p>\n<p><strong>En cas de vente du bien<\/strong><\/p>\n<p>Pour pr\u00e9server les droits du locataire sur les tiers qui auraient pu enregistrer leur droit sur la propri\u00e9t\u00e9, il n&rsquo;est plus n\u00e9cessaire que le bail soit enregistr\u00e9 au registre foncier, comme c&rsquo;\u00e9tait le cas jusqu&rsquo;\u00e0 pr\u00e9sent.<\/p>\n<p>Il convient de noter que tr\u00e8s peu de locataires ont inscrit ce droit au registre, car cela impliquait une d\u00e9pense suppl\u00e9mentaire qui n&rsquo;assurait gu\u00e8re une protection pendant une p\u00e9riode de trois ans.<\/p>\n<p>Il existe une s\u00e9rie de situations dans lesquelles la loi veut maintenant garantir le droit du locataire \u00e0 rester dans le logement pendant la p\u00e9riode minimale (cinq ou sept ans, selon le cas).<\/p>\n<p>Ainsi, en cas de vente du logement lou\u00e9 pendant les cinq premi\u00e8res ann\u00e9es du contrat (ou sept si le bailleur est une personne morale), le locataire a le droit de poursuivre le bail jusqu&rsquo;\u00e0 cinq ans ou sept ans, respectivement. Pendant cette p\u00e9riode, l&rsquo;acheteur subroge le propri\u00e9taire dans ses droits et obligations, m\u00eame s&rsquo;il a \u00e9t\u00e9 convenu dans le contrat de location que la vente de la maison mettrait fin au bail. De m\u00eame, en cas d&rsquo;ali\u00e9nation forc\u00e9e de la propri\u00e9t\u00e9 r\u00e9sultant d&rsquo;une saisie ou d&rsquo;une d\u00e9cision judiciaire.<\/p>\n<p>Si le locataire a convenu dans le contrat de bonne foi avec une personne qui appara\u00eet comme propri\u00e9taire du bien dans le registre foncier, ou qui appara\u00eet comme propri\u00e9taire en vertu d&rsquo;un \u00e9tat de fait dont la cr\u00e9ation est imputable au v\u00e9ritable propri\u00e9taire, il a le droit de rester dans la propri\u00e9t\u00e9 pendant la dur\u00e9e minimale (cinq ou sept ans).<\/p>\n<p><strong>Les processus d&rsquo;expulsion doivent inclure des services sociaux<\/strong><\/p>\n<p>Dans les proc\u00e9dures d&rsquo;expulsion de la r\u00e9sidence habituelle lou\u00e9e pour non-paiement, le tribunal informera automatiquement les services sociaux de l&rsquo;existence de cette proc\u00e9dure. Si les services sociaux informent le tribunal que le m\u00e9nage concern\u00e9 se trouve dans une situation de vuln\u00e9rabilit\u00e9 sociale ou \u00e9conomique, la proc\u00e9dure sera suspendue pour une p\u00e9riode maximale d&rsquo;un mois (trois mois si le propri\u00e9taire est une personne morale) jusqu&rsquo;\u00e0 ce que les mesures n\u00e9cessaires jug\u00e9es appropri\u00e9es par les services sociaux soient adopt\u00e9es.<\/p>\n<p><strong>Locations touristiques<\/strong><\/p>\n<p>Les communaut\u00e9s voisines ont le pouvoir de limiter le nombre d&rsquo;appartements de vacances dans leurs b\u00e2timents.<\/p>\n<p>Auparavant, il \u00e9tait imp\u00e9ratif que la modification soit unanime, de sorte que si le propri\u00e9taire de l&rsquo;appartement de vacances s&rsquo;opposait \u00e0 cette interdiction, la communaut\u00e9 de voisins ne pourrait pas bloquer la location de vacances.<\/p>\n<p>Maintenant, une majorit\u00e9 des trois cinqui\u00e8mes des propri\u00e9taires suffit pour modifier le statut de la communaut\u00e9 afin d&rsquo;interdire l&rsquo;apparition de tout appartement de vacances dans l&rsquo;immeuble.<\/p>\n<p>Avez-vous encore des doutes sur les nouveaux contrats de location et sur les cons\u00e9quences qu&rsquo;ils pourraient avoir pour vous en tant que bailleur ou locataire en Espagne ?<\/p>\n<p>Parlez-en \u00e0 Fuster &amp; Associates.<\/p>\n<p>Nous serons heureux de vous aider \u00e0 r\u00e9diger votre contrat et de vous guider tout au long du processus.<\/p>\n<p>Image principale : D\u00e9veloppement de Tindra Homes sur la Costa C\u00e1lida \u00a9TindraHomes.<\/p>\n<p>Nous souhaitons vous aider \u00e0 naviguer dans toutes les complexit\u00e9s juridiques qui accompagnent l&rsquo;achat de votre maison en Espagne, mais cet article est une information juridique et ne doit pas \u00eatre consid\u00e9r\u00e9 comme un conseil juridique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain. Il s&rsquo;agit d&rsquo;une traduction automatique en attente de r\u00e9vision. Le Conseil permanent du Tribunal g\u00e9n\u00e9ral espagnol a approuv\u00e9 la validation du d\u00e9cret-loi royal 7\/2019 sur les mesures urgentes en mati\u00e8re de logement et de loyer, qui [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[257],"tags":[],"class_list":["post-18291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-declaration-des-revenus-locatifs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouveaux contrats de bail en Espagne - A quoi devez-vous faire attention ? - Fuster &amp; Associates<\/title>\n<meta name=\"description\" content=\"Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouveaux contrats de bail en Espagne - A quoi devez-vous faire attention ?\" \/>\n<meta property=\"og:description\" content=\"Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuster &amp; Associates\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fusterspain\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-27T11:38:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-06T11:49:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuster-associates.com\/wp-content\/uploads\/2019\/05\/tindra-homes-post-alquiler.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jos\u00e9 Miguel Company\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Nouveaux contrats de bail en Espagne - A quoi devez-vous faire attention ?\" \/>\n<meta name=\"twitter:description\" content=\"Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.\" \/>\n<meta name=\"twitter:creator\" content=\"@FusterSpain\" \/>\n<meta name=\"twitter:site\" content=\"@FusterSpain\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos\u00e9 Miguel Company\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/\"},\"author\":{\"name\":\"Jos\u00e9 Miguel Company\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#\\\/schema\\\/person\\\/4d55f8f26cc137eeafc014c332c4e1bb\"},\"headline\":\"Nouveaux contrats de bail en Espagne &#8211; A quoi devez-vous faire attention ?\",\"datePublished\":\"2019-05-27T11:38:04+00:00\",\"dateModified\":\"2020-04-06T11:49:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/\"},\"wordCount\":1361,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuster-associates.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/tindra-homes-post-alquiler.jpg\",\"articleSection\":[\"D\u00e9claration des Revenus Locatifs\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/\",\"name\":\"Nouveaux contrats de bail en Espagne - A quoi devez-vous faire attention ? - Fuster &amp; Associates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuster-associates.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/tindra-homes-post-alquiler.jpg\",\"datePublished\":\"2019-05-27T11:38:04+00:00\",\"dateModified\":\"2020-04-06T11:49:37+00:00\",\"description\":\"Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/tindra-homes-post-alquiler.jpg\",\"contentUrl\":\"https:\\\/\\\/fuster-associates.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/tindra-homes-post-alquiler.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/blog\\\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouveaux contrats de bail en Espagne &#8211; A quoi devez-vous faire attention ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/\",\"name\":\"Fuster & Associates\",\"description\":\"Property Solicitors\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#organization\",\"name\":\"FUSTER & ASSOCIATES\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo-fuster-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuster-associates.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo-fuster-1.jpeg\",\"width\":180,\"height\":113,\"caption\":\"FUSTER & ASSOCIATES\"},\"image\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fusterspain\\\/\",\"https:\\\/\\\/x.com\\\/FusterSpain\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC2-kNuL1SoqlFizI47hmIOQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fuster-&-associates\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/fr\\\/#\\\/schema\\\/person\\\/4d55f8f26cc137eeafc014c332c4e1bb\",\"name\":\"Jos\u00e9 Miguel Company\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04142bfa1a22cc524d73b33f44758c597efc445436dc2b56b75aa4fe234336d1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04142bfa1a22cc524d73b33f44758c597efc445436dc2b56b75aa4fe234336d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04142bfa1a22cc524d73b33f44758c597efc445436dc2b56b75aa4fe234336d1?s=96&d=mm&r=g\",\"caption\":\"Jos\u00e9 Miguel Company\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouveaux contrats de bail en Espagne - A quoi devez-vous faire attention ? - Fuster &amp; Associates","description":"Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouveaux contrats de bail en Espagne - A quoi devez-vous faire attention ?","og_description":"Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.","og_url":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/","og_site_name":"Fuster &amp; Associates","article_publisher":"https:\/\/www.facebook.com\/fusterspain\/","article_published_time":"2019-05-27T11:38:04+00:00","article_modified_time":"2020-04-06T11:49:37+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2019\/05\/tindra-homes-post-alquiler.jpg","type":"image\/jpeg"}],"author":"Jos\u00e9 Miguel Company","twitter_card":"summary_large_image","twitter_title":"Nouveaux contrats de bail en Espagne - A quoi devez-vous faire attention ?","twitter_description":"Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.","twitter_creator":"@FusterSpain","twitter_site":"@FusterSpain","twitter_misc":{"\u00c9crit par":"Jos\u00e9 Miguel Company","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/#article","isPartOf":{"@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/"},"author":{"name":"Jos\u00e9 Miguel Company","@id":"https:\/\/fuster-associates.com\/fr\/#\/schema\/person\/4d55f8f26cc137eeafc014c332c4e1bb"},"headline":"Nouveaux contrats de bail en Espagne &#8211; A quoi devez-vous faire attention ?","datePublished":"2019-05-27T11:38:04+00:00","dateModified":"2020-04-06T11:49:37+00:00","mainEntityOfPage":{"@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/"},"wordCount":1361,"commentCount":0,"publisher":{"@id":"https:\/\/fuster-associates.com\/fr\/#organization"},"image":{"@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/#primaryimage"},"thumbnailUrl":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2019\/05\/tindra-homes-post-alquiler.jpg","articleSection":["D\u00e9claration des Revenus Locatifs"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/","url":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/","name":"Nouveaux contrats de bail en Espagne - A quoi devez-vous faire attention ? - Fuster &amp; Associates","isPartOf":{"@id":"https:\/\/fuster-associates.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/#primaryimage"},"image":{"@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/#primaryimage"},"thumbnailUrl":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2019\/05\/tindra-homes-post-alquiler.jpg","datePublished":"2019-05-27T11:38:04+00:00","dateModified":"2020-04-06T11:49:37+00:00","description":"Les nouveaux baux sign\u00e9s en Espagne seront dor\u00e9navant bas\u00e9s sur la r\u00e9forme de la loi sur le bail urbain.","breadcrumb":{"@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/#primaryimage","url":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2019\/05\/tindra-homes-post-alquiler.jpg","contentUrl":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2019\/05\/tindra-homes-post-alquiler.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/fuster-associates.com\/fr\/blog\/nouveaux-contrats-de-bail-en-espagne-a-quoi-devez-vous-faire-attention\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fuster-associates.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouveaux contrats de bail en Espagne &#8211; A quoi devez-vous faire attention ?"}]},{"@type":"WebSite","@id":"https:\/\/fuster-associates.com\/fr\/#website","url":"https:\/\/fuster-associates.com\/fr\/","name":"Fuster & Associates","description":"Property Solicitors","publisher":{"@id":"https:\/\/fuster-associates.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuster-associates.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fuster-associates.com\/fr\/#organization","name":"FUSTER & ASSOCIATES","url":"https:\/\/fuster-associates.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fuster-associates.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2018\/08\/logo-fuster-1.jpeg","contentUrl":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2018\/08\/logo-fuster-1.jpeg","width":180,"height":113,"caption":"FUSTER & ASSOCIATES"},"image":{"@id":"https:\/\/fuster-associates.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fusterspain\/","https:\/\/x.com\/FusterSpain","https:\/\/www.youtube.com\/channel\/UC2-kNuL1SoqlFizI47hmIOQ","https:\/\/www.linkedin.com\/company\/fuster-&-associates\/"]},{"@type":"Person","@id":"https:\/\/fuster-associates.com\/fr\/#\/schema\/person\/4d55f8f26cc137eeafc014c332c4e1bb","name":"Jos\u00e9 Miguel Company","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/04142bfa1a22cc524d73b33f44758c597efc445436dc2b56b75aa4fe234336d1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04142bfa1a22cc524d73b33f44758c597efc445436dc2b56b75aa4fe234336d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04142bfa1a22cc524d73b33f44758c597efc445436dc2b56b75aa4fe234336d1?s=96&d=mm&r=g","caption":"Jos\u00e9 Miguel Company"}}]}},"_links":{"self":[{"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/posts\/18291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/comments?post=18291"}],"version-history":[{"count":0,"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/posts\/18291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/media\/15503"}],"wp:attachment":[{"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/media?parent=18291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/categories?post=18291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuster-associates.com\/fr\/wp-json\/wp\/v2\/tags?post=18291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}