{"id":298,"count":3,"description":"","link":"https:\/\/fuster-associates.com\/de\/blog\/category\/goldenes-visum\/","name":"Goldenes Visum","slug":"goldenes-visum","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Goldenes Visum - Fuster &amp; Associates<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Goldenes Visum - Fuster &amp; Associates\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuster-associates.com\/de\/blog\/category\/goldenes-visum\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuster &amp; Associates\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuster-associates.com\/wp-content\/uploads\/2020\/02\/slide-fuster-standard.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FusterSpain\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/blog\\\/category\\\/goldenes-visum\\\/\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/blog\\\/category\\\/goldenes-visum\\\/\",\"name\":\"Goldenes Visum - Fuster &amp; Associates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/blog\\\/category\\\/goldenes-visum\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/blog\\\/category\\\/goldenes-visum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Goldenes Visum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/\",\"name\":\"Fuster & Associates\",\"description\":\"Property Solicitors\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/#organization\",\"name\":\"FUSTER & ASSOCIATES\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuster-associates.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo-fuster-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuster-associates.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/logo-fuster-1.jpeg\",\"width\":180,\"height\":113,\"caption\":\"FUSTER & ASSOCIATES\"},\"image\":{\"@id\":\"https:\\\/\\\/fuster-associates.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fusterspain\\\/\",\"https:\\\/\\\/x.com\\\/FusterSpain\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC2-kNuL1SoqlFizI47hmIOQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fuster-&-associates\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Goldenes Visum - Fuster &amp; Associates","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Goldenes Visum - Fuster &amp; Associates","og_url":"https:\/\/fuster-associates.com\/de\/blog\/category\/goldenes-visum\/","og_site_name":"Fuster &amp; Associates","og_image":[{"width":1920,"height":1280,"url":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2020\/02\/slide-fuster-standard.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@FusterSpain","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fuster-associates.com\/de\/blog\/category\/goldenes-visum\/","url":"https:\/\/fuster-associates.com\/de\/blog\/category\/goldenes-visum\/","name":"Goldenes Visum - Fuster &amp; Associates","isPartOf":{"@id":"https:\/\/fuster-associates.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/fuster-associates.com\/de\/blog\/category\/goldenes-visum\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/fuster-associates.com\/de\/blog\/category\/goldenes-visum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fuster-associates.com\/de\/"},{"@type":"ListItem","position":2,"name":"Goldenes Visum"}]},{"@type":"WebSite","@id":"https:\/\/fuster-associates.com\/de\/#website","url":"https:\/\/fuster-associates.com\/de\/","name":"Fuster & Associates","description":"Property Solicitors","publisher":{"@id":"https:\/\/fuster-associates.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuster-associates.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/fuster-associates.com\/de\/#organization","name":"FUSTER & ASSOCIATES","url":"https:\/\/fuster-associates.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/fuster-associates.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2018\/08\/logo-fuster-1.jpeg","contentUrl":"https:\/\/fuster-associates.com\/wp-content\/uploads\/2018\/08\/logo-fuster-1.jpeg","width":180,"height":113,"caption":"FUSTER & ASSOCIATES"},"image":{"@id":"https:\/\/fuster-associates.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fusterspain\/","https:\/\/x.com\/FusterSpain","https:\/\/www.youtube.com\/channel\/UC2-kNuL1SoqlFizI47hmIOQ","https:\/\/www.linkedin.com\/company\/fuster-&-associates\/"]}]}},"_links":{"self":[{"href":"https:\/\/fuster-associates.com\/de\/wp-json\/wp\/v2\/categories\/298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuster-associates.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/fuster-associates.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/fuster-associates.com\/de\/wp-json\/wp\/v2\/posts?categories=298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}